{"id":24642,"date":"2024-04-19T12:35:43","date_gmt":"2024-04-19T12:35:43","guid":{"rendered":"https:\/\/livedemo.top\/supplements\/product\/natrol-melatonin-1-mg-1x90-tab\/"},"modified":"2024-04-19T12:35:44","modified_gmt":"2024-04-19T12:35:44","slug":"natrol-melatonin-1-mg-1x90-tab","status":"publish","type":"product","link":"https:\/\/livedemo.top\/supplements\/product\/natrol-melatonin-1-mg-1x90-tab\/","title":{"rendered":"Natrol Melatonin 1 Mg (1&#215;90 TAB)"},"content":{"rendered":"<p>ANTISTRESS &#038; RELAXATION<\/p>\n<p>Manufacturer: Natrol<\/p>\n<p>UPC: 047469004651<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANTISTRESS &#038; RELAXATION Manufacturer: Natrol UPC: 047469004651<\/p>\n","protected":false},"featured_media":27433,"comment_status":"closed","ping_status":"open","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[1407,1381],"product_tag":[],"class_list":{"0":"post-24642","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-antistress-relaxation","7":"product_cat-specific-formulas","9":"first","10":"instock","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Natrol Melatonin 1 Mg (1x90 TAB) - Sports Supplements<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/livedemo.top\/supplements\/product\/natrol-melatonin-1-mg-1x90-tab\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Natrol Melatonin 1 Mg (1x90 TAB) - Sports Supplements\" \/>\n<meta property=\"og:description\" content=\"ANTISTRESS &#038; RELAXATION Manufacturer: Natrol UPC: 047469004651\" \/>\n<meta property=\"og:url\" content=\"https:\/\/livedemo.top\/supplements\/product\/natrol-melatonin-1-mg-1x90-tab\/\" \/>\n<meta property=\"og:site_name\" content=\"Sports Supplements\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-19T12:35:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn10.bigcommerce.com\/s-ex8q3n8\/products\/16803\/images\/111057\/600c797f-4327-4473-b2d1-0c2469a76e25.3ac6eb623c85ac51a18c090e16e13a85__08102.1655378190.1280.1280.png?c=2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cdn10.bigcommerce.com\/s-ex8q3n8\/products\/16803\/images\/111057\/600c797f-4327-4473-b2d1-0c2469a76e25.3ac6eb623c85ac51a18c090e16e13a85__08102.1655378190.1280.1280.png?c=2\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/product\\\/natrol-melatonin-1-mg-1x90-tab\\\/\",\"url\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/product\\\/natrol-melatonin-1-mg-1x90-tab\\\/\",\"name\":\"Natrol Melatonin 1 Mg (1x90 TAB) - Sports Supplements\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/product\\\/natrol-melatonin-1-mg-1x90-tab\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/product\\\/natrol-melatonin-1-mg-1x90-tab\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn10.bigcommerce.com\\\/s-ex8q3n8\\\/products\\\/16803\\\/images\\\/111057\\\/600c797f-4327-4473-b2d1-0c2469a76e25.3ac6eb623c85ac51a18c090e16e13a85__08102.1655378190.1280.1280.png?c=2\",\"datePublished\":\"2024-04-19T12:35:43+00:00\",\"dateModified\":\"2024-04-19T12:35:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/product\\\/natrol-melatonin-1-mg-1x90-tab\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/livedemo.top\\\/supplements\\\/product\\\/natrol-melatonin-1-mg-1x90-tab\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/product\\\/natrol-melatonin-1-mg-1x90-tab\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn10.bigcommerce.com\\\/s-ex8q3n8\\\/products\\\/16803\\\/images\\\/111057\\\/600c797f-4327-4473-b2d1-0c2469a76e25.3ac6eb623c85ac51a18c090e16e13a85__08102.1655378190.1280.1280.png?c=2\",\"contentUrl\":\"https:\\\/\\\/cdn10.bigcommerce.com\\\/s-ex8q3n8\\\/products\\\/16803\\\/images\\\/111057\\\/600c797f-4327-4473-b2d1-0c2469a76e25.3ac6eb623c85ac51a18c090e16e13a85__08102.1655378190.1280.1280.png?c=2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/product\\\/natrol-melatonin-1-mg-1x90-tab\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Natrol Melatonin 1 Mg (1&#215;90 TAB)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/#website\",\"url\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/\",\"name\":\"Security & Surveillance Store\",\"description\":\"Online Sports Supplements Store\",\"publisher\":{\"@id\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/#organization\",\"name\":\"Security & Surveillance Store\",\"url\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/SC2.png\",\"contentUrl\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/SC2.png\",\"width\":400,\"height\":145,\"caption\":\"Security & Surveillance Store\"},\"image\":{\"@id\":\"https:\\\/\\\/livedemo.top\\\/supplements\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Natrol Melatonin 1 Mg (1x90 TAB) - Sports Supplements","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/livedemo.top\/supplements\/product\/natrol-melatonin-1-mg-1x90-tab\/","og_locale":"en_US","og_type":"article","og_title":"Natrol Melatonin 1 Mg (1x90 TAB) - Sports Supplements","og_description":"ANTISTRESS &#038; RELAXATION Manufacturer: Natrol UPC: 047469004651","og_url":"https:\/\/livedemo.top\/supplements\/product\/natrol-melatonin-1-mg-1x90-tab\/","og_site_name":"Sports Supplements","article_modified_time":"2024-04-19T12:35:44+00:00","og_image":[{"url":"https:\/\/cdn10.bigcommerce.com\/s-ex8q3n8\/products\/16803\/images\/111057\/600c797f-4327-4473-b2d1-0c2469a76e25.3ac6eb623c85ac51a18c090e16e13a85__08102.1655378190.1280.1280.png?c=2","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cdn10.bigcommerce.com\/s-ex8q3n8\/products\/16803\/images\/111057\/600c797f-4327-4473-b2d1-0c2469a76e25.3ac6eb623c85ac51a18c090e16e13a85__08102.1655378190.1280.1280.png?c=2","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/livedemo.top\/supplements\/product\/natrol-melatonin-1-mg-1x90-tab\/","url":"https:\/\/livedemo.top\/supplements\/product\/natrol-melatonin-1-mg-1x90-tab\/","name":"Natrol Melatonin 1 Mg (1x90 TAB) - Sports Supplements","isPartOf":{"@id":"https:\/\/livedemo.top\/supplements\/#website"},"primaryImageOfPage":{"@id":"https:\/\/livedemo.top\/supplements\/product\/natrol-melatonin-1-mg-1x90-tab\/#primaryimage"},"image":{"@id":"https:\/\/livedemo.top\/supplements\/product\/natrol-melatonin-1-mg-1x90-tab\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn10.bigcommerce.com\/s-ex8q3n8\/products\/16803\/images\/111057\/600c797f-4327-4473-b2d1-0c2469a76e25.3ac6eb623c85ac51a18c090e16e13a85__08102.1655378190.1280.1280.png?c=2","datePublished":"2024-04-19T12:35:43+00:00","dateModified":"2024-04-19T12:35:44+00:00","breadcrumb":{"@id":"https:\/\/livedemo.top\/supplements\/product\/natrol-melatonin-1-mg-1x90-tab\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/livedemo.top\/supplements\/product\/natrol-melatonin-1-mg-1x90-tab\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/livedemo.top\/supplements\/product\/natrol-melatonin-1-mg-1x90-tab\/#primaryimage","url":"https:\/\/cdn10.bigcommerce.com\/s-ex8q3n8\/products\/16803\/images\/111057\/600c797f-4327-4473-b2d1-0c2469a76e25.3ac6eb623c85ac51a18c090e16e13a85__08102.1655378190.1280.1280.png?c=2","contentUrl":"https:\/\/cdn10.bigcommerce.com\/s-ex8q3n8\/products\/16803\/images\/111057\/600c797f-4327-4473-b2d1-0c2469a76e25.3ac6eb623c85ac51a18c090e16e13a85__08102.1655378190.1280.1280.png?c=2"},{"@type":"BreadcrumbList","@id":"https:\/\/livedemo.top\/supplements\/product\/natrol-melatonin-1-mg-1x90-tab\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/livedemo.top\/supplements\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/livedemo.top\/supplements\/shop\/"},{"@type":"ListItem","position":3,"name":"Natrol Melatonin 1 Mg (1&#215;90 TAB)"}]},{"@type":"WebSite","@id":"https:\/\/livedemo.top\/supplements\/#website","url":"https:\/\/livedemo.top\/supplements\/","name":"Security & Surveillance Store","description":"Online Sports Supplements Store","publisher":{"@id":"https:\/\/livedemo.top\/supplements\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/livedemo.top\/supplements\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/livedemo.top\/supplements\/#organization","name":"Security & Surveillance Store","url":"https:\/\/livedemo.top\/supplements\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/livedemo.top\/supplements\/#\/schema\/logo\/image\/","url":"https:\/\/livedemo.top\/supplements\/wp-content\/uploads\/2023\/04\/SC2.png","contentUrl":"https:\/\/livedemo.top\/supplements\/wp-content\/uploads\/2023\/04\/SC2.png","width":400,"height":145,"caption":"Security & Surveillance Store"},"image":{"@id":"https:\/\/livedemo.top\/supplements\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/livedemo.top\/supplements\/wp-json\/wp\/v2\/product\/24642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livedemo.top\/supplements\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/livedemo.top\/supplements\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/livedemo.top\/supplements\/wp-json\/wp\/v2\/comments?post=24642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/livedemo.top\/supplements\/wp-json\/wp\/v2\/media\/27433"}],"wp:attachment":[{"href":"https:\/\/livedemo.top\/supplements\/wp-json\/wp\/v2\/media?parent=24642"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/livedemo.top\/supplements\/wp-json\/wp\/v2\/product_brand?post=24642"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/livedemo.top\/supplements\/wp-json\/wp\/v2\/product_cat?post=24642"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/livedemo.top\/supplements\/wp-json\/wp\/v2\/product_tag?post=24642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}