{"id":39803,"date":"2026-03-26T11:22:54","date_gmt":"2026-03-26T11:22:54","guid":{"rendered":"https:\/\/livedemo.top\/drones\/product\/darwinfpv-cineape20-analog-2-inch-3s-f4-15a-elrs-rtf-cinewhoop-fpv-racing-drones-gps-with-tx8-elrs-transmitter-mini-3-inch-5-8ghz-40ch-fpv-goggles\/"},"modified":"2026-03-26T11:22:55","modified_gmt":"2026-03-26T11:22:55","slug":"darwinfpv-cineape20-analog-2-inch-3s-f4-15a-elrs-rtf-cinewhoop-fpv-racing-drones-gps-with-tx8-elrs-transmitter-mini-3-inch-5-8ghz-40ch-fpv-goggles","status":"publish","type":"product","link":"https:\/\/livedemo.top\/drones\/product\/darwinfpv-cineape20-analog-2-inch-3s-f4-15a-elrs-rtf-cinewhoop-fpv-racing-drones-gps-with-tx8-elrs-transmitter-mini-3-inch-5-8ghz-40ch-fpv-goggles\/","title":{"rendered":"DarwinFPV CineApe20 Analog 2 Inch 3S F4 15A ELRS RTF Cinewhoop FPV Racing Drones GPS with TX8 ELRS Transmitter Mini 3 Inch 5.8GHz 40Ch FPV Goggles"},"content":{"rendered":"<div id='specification'><\/div>\n<div id='specification_end'><\/div>\n<p class='MsoNormal'><b>Description:<\/b><\/p>\n<p class='MsoNormal'>Designed specifically for FPV beginners, the CineApe20 FPV targets key pain points: &#8216;hard to carry, easy to break in crashes, complicated to operate&#8217;. Its pocket-sized body works for both indoor shooting and outdoor flying; TPU material eliminates the need for shock-absorbing balls to prevent the &#8216;jello effect&#8217; while protecting the device. The enclosed design plus crash-resistant Bling 1103 motor (2-3S, 5.5min flight time\/6:1 thrust-to-weight ratio) boosts durability. Front-mounted GPS avoids interference, modular plug-and-play design lets beginners replace parts easily, and dual mounting holes on the top plate are compatible with all video transmitters.<o_p><\/o_p><\/p>\n<p class='MsoNormal'>Supporting gear fixes &#8216;short control range, poor visibility&#8217;: ELRS TX8 remote supports simulators, with 2.4G RF module for over 2KM control range (covers 90% of beginner scenarios); goggles come in analog (EV800DM 5.8G, lightweight, stable signal\/low latency) and HD (DJI N3) versions for different needs. Low entry barrier &amp; high reliability let beginners enjoy FPV flying easily.<o_p><\/o_p><\/p>\n<p class='MsoNormal'>&nbsp;<\/p>\n<p class='MsoNormal'><b>Feature:<\/b><o_p><\/o_p><\/p>\n<p class='MsoNormal'>1. CineApe20 is plam-sized, very convenient to carry. It is suitable for both indoor stable shooting and outdoor dynamic flying. It is an ideal choice for beginners to enter FPV.<o_p><\/o_p><\/p>\n<p class='MsoNormal'>2. Differenrt frome Pavo20, CineApe20 adopts TPU material, which can filter low-frequency vibrations without shock-absorbing balls and stay away from rolling shutter. The plate reserves two sets of adjustment mount holes in the front and back. When installed in the front holes, the protective guard cannot be seen even in the DJI O3 ultra-wide-angle mode. In addition, TPU is softer and durabl, which can better protect DJI O3 from damage caused by crashes.<o_p><\/o_p><\/p>\n<p class='MsoNormal'>3. The body adopts an integrated and closed design with smooth body lines for smoother flight. At the same time, it reduces the risk of damage caused by the entry of debris and is more durabl\uff1b<o_p><\/o_p><\/p>\n<p class='MsoNormal'>4. The whole series is equipped with GPS, and the front GPS can better stay away from antenna interference. In case of emergency rescue, it is better to be safe than sorry\uff01<o_p><\/o_p><\/p>\n<p class='MsoNormal'>5. The brand-new Bling series 1103 motor, we have specially reduced the stiffness of the motor shaft and is more resistant to crashes. It supports 2-3S batteries, and can achieve 5.5 minutes of flight time and a thrust-to-weight ratio of 6:1, achieving a perfect balance between endurance and performance\uff1b<o_p><\/o_p><\/p>\n<p class='MsoNormal'>6. The whole drone adopts a modular full plug-and-pull design, and the camera,vtx, and motors are plug-and-play. It is convenient for maintenance and replacement of components, and more easier for beginners to get started\uff1b<o_p><\/o_p><\/p>\n<p class='MsoNormal'>7. The top plate reserves two kinds of mount holes, 20\u00d720 and 25.5\u00d725.5, which can install analog vtx, DJI O3, RunCam Link, Walksnail, OpenIPC, and all vtxs such as the not-yet-released DJI O4\uff1b<o_p><\/o_p><\/p>\n<p class='MsoNormal'>8. The ELRS TX8 remote controller natively supports a variety of popular simulators. It has a built-in ELRS 2.4G 100mW RF module and offers a control range of over 2KM, which can meet 90% of the usage scenarios for beginners, making it easier to enjoy the fun of flying.<o_p><\/o_p><\/p>\n<p class='MsoNormal'>9. The analog version is equipped with the EV800DM 5.8G 3-inch goggles (featuring lightweight portability + dual antennas for stable signal + 10ms low latency), while the HD version comes with DJI N3 goggles. Both options meet the demand for clear flying vision in different scenarios.<o_p><\/o_p><\/p>\n<p class='MsoNormal'>&nbsp;<\/p>\n<p class='MsoNormal'><b>Specification:<\/b><o_p><\/o_p><\/p>\n<p class='MsoNormal'>Brand: DarwinFPV<o_p><\/o_p><\/p>\n<p class='MsoNormal'>Model: CineApe20<\/p>\n<p class='MsoNormal'>Item Name: 2 Inch 3S Analog RTF FPV Drone<\/p>\n<table class='MsoTableGrid' border='1' cellspacing='0' style='border: none;'>\n<tbody>\n<tr style='height:4.5000pt;'>\n<td width='379' valign='top' colspan='2' style='width:284.3500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:1.0000pt solid windowtext;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>RTF Version<o_p><\/o_p><\/p>\n<\/td>\n<td width='183' valign='top' style='width:137.5000pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:1.0000pt solid windowtext;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>CineApe20 Analog RTF<o_p><\/o_p><\/p>\n<\/td>\n<td width='206' valign='top' colspan='2' style='width:154.8000pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:1.0000pt solid windowtext;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>CineApe20 without O4 Pro RTF <o_p><\/o_p><\/p>\n<\/td>\n<td width='176' valign='top' style='width:132.0500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:1.0000pt solid windowtext;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>CineApe20 O4 Pro RTF<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='186' valign='top' rowspan='15' style='width:139.7000pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:none;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Drone Specification<o_p><\/o_p><\/p>\n<\/td>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Name: <o_p><\/o_p><\/p>\n<\/td>\n<td width='183' valign='top' style='width:137.5000pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>CineApe20 Analog<o_p><\/o_p><\/p>\n<\/td>\n<td width='206' valign='top' colspan='2' style='width:154.8000pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>CineApe20 without O4 Pro RTF <o_p><\/o_p><\/p>\n<\/td>\n<td width='176' valign='top' style='width:132.0500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:1.0000pt solid windowtext;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>CineApe20&nbsp;O4 Pro<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Video: <o_p><\/o_p><\/p>\n<\/td>\n<td width='183' valign='top' style='width:137.5000pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>NONE<o_p><\/o_p><\/p>\n<\/td>\n<td width='206' valign='top' colspan='2' style='width:154.8000pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>NONE<o_p><\/o_p><\/p>\n<\/td>\n<td width='176' valign='top' style='width:132.0500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>4K\/120fps<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Camera:<o_p><\/o_p><\/p>\n<\/td>\n<td width='183' valign='top' style='width:137.5000pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Caddx Ant<o_p><\/o_p><\/p>\n<\/td>\n<td width='206' valign='top' colspan='2' style='width:154.8000pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>NONE<o_p><\/o_p><\/p>\n<\/td>\n<td width='176' valign='top' style='width:132.0500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>DJI O4 Air Unit Pro<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>VTX: <o_p><\/o_p><\/p>\n<\/td>\n<td width='183' valign='top' style='width:137.5000pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>DarwinFPV 25\/200\/400\/600mW VTX<o_p><\/o_p><\/p>\n<\/td>\n<td width='206' valign='top' colspan='2' style='width:154.8000pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>NONE<o_p><\/o_p><\/p>\n<\/td>\n<td width='176' valign='top' style='width:132.0500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>DJI O4 Air Unit Pro<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Farthest Flight Distance <o_p><\/o_p><\/p>\n<p class='MsoNormal'>(No Interference environment): <o_p><\/o_p><\/p>\n<\/td>\n<td width='183' valign='top' style='width:137.5000pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>1.5KM<o_p><\/o_p><\/p>\n<\/td>\n<td width='206' valign='top' colspan='2' style='width:154.8000pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>\/<o_p><\/o_p><\/p>\n<\/td>\n<td width='176' valign='top' style='width:132.0500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>10KM<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Max Horizontal Flight Speed: <o_p><\/o_p><\/p>\n<\/td>\n<td width='565' valign='top' colspan='4' style='width:424.3500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>45km\/h<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>AIO:<o_p><\/o_p><\/p>\n<\/td>\n<td width='565' valign='top' colspan='4' style='width:424.3500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>DarwinFPV F411 15A ELRS AIO<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Receiver:<o_p><\/o_p><\/p>\n<\/td>\n<td width='565' valign='top' colspan='4' style='width:424.3500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Onboard SPI ELRS 2.4G<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr style='height:13.8500pt;'>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>GPS: <o_p><\/o_p><\/p>\n<\/td>\n<td width='565' valign='top' colspan='4' style='width:424.3500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>M10 Mini GPS<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Motor:<o_p><\/o_p><\/p>\n<\/td>\n<td width='565' valign='top' colspan='4' style='width:424.3500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>DarwinFPV Bling 1103-8000KV<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Propeller:<o_p><\/o_p><\/p>\n<\/td>\n<td width='565' valign='top' colspan='4' style='width:424.3500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>2023-3 Transparent Gray<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Frame Type:<o_p><\/o_p><\/p>\n<\/td>\n<td width='565' valign='top' colspan='4' style='width:424.3500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Ture-X <o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr style='height:15.7000pt;'>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Wheelbase:<o_p><\/o_p><\/p>\n<\/td>\n<td width='565' valign='top' colspan='4' style='width:424.3500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>90mm<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Arm Thickness: <o_p><\/o_p><\/p>\n<\/td>\n<td width='565' valign='top' colspan='4' style='width:424.3500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>2mm<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Battery Life: <o_p><\/o_p><\/p>\n<\/td>\n<td width='565' valign='top' colspan='4' style='width:424.3500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>5.5mins(with 3S 500mAh 100C battery)<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='186' valign='top' rowspan='13' style='width:139.7000pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:none;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>TX8 ELRS Transmitter<o_p><\/o_p><\/p>\n<\/td>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Frequency Range: <o_p><\/o_p><\/p>\n<\/td>\n<td width='565' valign='top' colspan='4' style='width:424.3500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>2.4GHz ISM<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Transmit Module:<o_p><\/o_p><\/p>\n<\/td>\n<td width='565' valign='top' colspan='4' style='width:424.3500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>ExpressLRS (ELRS SX1280)<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Distance: <o_p><\/o_p><\/p>\n<\/td>\n<td width='565' valign='top' colspan='4' style='width:424.3500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>&gt;2KM<o_p><\/o_p><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width='192' valign='top' style='width:144.6500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt;mso-border-bottom-alt:0.5000pt solid windowtext;'>\n<p class='MsoNormal'>Joystick: <o_p><\/o_p><\/p>\n<\/td>\n<td width='565' valign='top' colspan='4' style='width:424.3500pt;padding:0.0000pt 5.4000pt 0.0000pt 5.4000pt ;border-left:1.0000pt solid windowtext;&lt;br&gt;mso-border-left-alt:0.5000pt solid windowtext;border-right:1.0000pt solid windowtext;mso-border-right-alt:0.5000pt solid windowtext;&lt;br&gt;border-top:none;mso-border-top-alt:0.5000pt solid windowtext;border-bottom:1.0000pt solid windowtext;&lt;br&gt; \n\n","protected":false},"excerpt":{"rendered":"<p>Description: Designed specifically for FPV beginners, the CineApe20 FPV targets key pain points: &#8216;hard to carry, easy to break in crashes, complicated to operate&#8217;. Its pocket-sized body works for both indoor shooting and outdoor flying; TPU material eliminates the need for shock-absorbing balls to prevent the &#8216;jello effect&#8217; while protecting the device. The enclosed design [&hellip;]<\/p>\n","protected":false},"featured_media":39804,"comment_status":"closed","ping_status":"open","template":"","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":""},"product_brand":[],"product_cat":[1565,1552,1551],"product_tag":[],"class_list":{"0":"post-39803","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-fpv-racing-drone","7":"product_cat-rc-drones","8":"product_cat-toys-hobbies-and-robot","9":"pa_version-analog","11":"entry","12":"has-media","14":"first","15":"instock","16":"purchasable","17":"product-type-simple","18":"has-product-nav","19":"col","20":"span_1_of_3","21":"owp-content-center","22":"owp-thumbs-layout-horizontal","23":"owp-btn-normal","24":"owp-tabs-layout-horizontal","25":"has-no-thumbnails"},"_links":{"self":[{"href":"https:\/\/livedemo.top\/drones\/wp-json\/wp\/v2\/product\/39803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livedemo.top\/drones\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/livedemo.top\/drones\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/livedemo.top\/drones\/wp-json\/wp\/v2\/comments?post=39803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/livedemo.top\/drones\/wp-json\/wp\/v2\/media\/39804"}],"wp:attachment":[{"href":"https:\/\/livedemo.top\/drones\/wp-json\/wp\/v2\/media?parent=39803"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/livedemo.top\/drones\/wp-json\/wp\/v2\/product_brand?post=39803"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/livedemo.top\/drones\/wp-json\/wp\/v2\/product_cat?post=39803"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/livedemo.top\/drones\/wp-json\/wp\/v2\/product_tag?post=39803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}